{"id":75122,"date":"2022-04-18T11:16:16","date_gmt":"2022-04-18T11:16:16","guid":{"rendered":"https:\/\/benoit-barbagli.com\/articles\/sysiphe-collectif-2\/"},"modified":"2022-04-18T11:16:16","modified_gmt":"2022-04-18T11:16:16","slug":"sysiphe-collectif-2","status":"publish","type":"product","link":"https:\/\/benoit-barbagli.com\/articles\/sysiphe-collectif-2\/","title":{"rendered":"Sysiphe collectif"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Sysiphe collectif, 2021<br \/>\nMythologie Subaquatique<br \/>\nPhotographie num\u00e9rique<br \/>\nPapier photo classique brillant RC 220g Plexi 3mm pour Face Arri\u00e8re Plexi 3mm Anti-Reflet pour Face Avant Ch\u00e2ssis rentrant Aluminium<br \/>\n120 \u00d7 79<br \/>\n5 exemplaires<br \/>\nAvec son certificat d\u2019authenticit\u00e9<\/p>\n","protected":false},"featured_media":75118,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[89,90],"product_tag":[],"class_list":["post-75122","product","type-product","status-publish","has-post-thumbnail","product_cat-oeuvres-originales","product_cat-photographie","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sysiphe collectif - benoit-barbagli.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/benoit-barbagli.com\/articles\/sysiphe-collectif-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sysiphe collectif - benoit-barbagli.com\" \/>\n<meta property=\"og:description\" content=\"Sysiphe collectif, 2021 Mythologie Subaquatique Photographie num\u00e9rique Papier photo classique brillant RC 220g Plexi 3mm pour Face Arri\u00e8re Plexi 3mm Anti-Reflet pour Face Avant Ch\u00e2ssis rentrant Aluminium 120 \u00d7 79 5 exemplaires Avec son certificat d\u2019authenticit\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/benoit-barbagli.com\/articles\/sysiphe-collectif-2\/\" \/>\n<meta property=\"og:site_name\" content=\"benoit-barbagli.com\" \/>\n<meta property=\"og:image\" content=\"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2022\/04\/DJI_0837-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/articles\\\/sysiphe-collectif-2\\\/\",\"url\":\"https:\\\/\\\/benoit-barbagli.com\\\/articles\\\/sysiphe-collectif-2\\\/\",\"name\":\"Sysiphe collectif - benoit-barbagli.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/articles\\\/sysiphe-collectif-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/articles\\\/sysiphe-collectif-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DJI_0837-scaled-1.jpg\",\"datePublished\":\"2022-04-18T11:16:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/articles\\\/sysiphe-collectif-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/benoit-barbagli.com\\\/articles\\\/sysiphe-collectif-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/articles\\\/sysiphe-collectif-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DJI_0837-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DJI_0837-scaled-1.jpg\",\"width\":2560,\"height\":1680},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/articles\\\/sysiphe-collectif-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"store\",\"item\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sysiphe collectif\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/\",\"name\":\"benoit-barbagli.com\",\"description\":\"Sous le chaos, la vie\",\"publisher\":{\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/#\\\/schema\\\/person\\\/78c8df9be07e5f4f79d983f84aafeefd\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/#\\\/schema\\\/person\\\/78c8df9be07e5f4f79d983f84aafeefd\",\"name\":\"benoitbarbagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Sisyphe-V-V3-final-scaled.jpg\",\"url\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Sisyphe-V-V3-final-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Sisyphe-V-V3-final-scaled.jpg\",\"width\":1713,\"height\":2560,\"caption\":\"benoitbarbagli\"},\"logo\":{\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Sisyphe-V-V3-final-scaled.jpg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sysiphe collectif - benoit-barbagli.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/benoit-barbagli.com\/articles\/sysiphe-collectif-2\/","og_locale":"en_US","og_type":"article","og_title":"Sysiphe collectif - benoit-barbagli.com","og_description":"Sysiphe collectif, 2021 Mythologie Subaquatique Photographie num\u00e9rique Papier photo classique brillant RC 220g Plexi 3mm pour Face Arri\u00e8re Plexi 3mm Anti-Reflet pour Face Avant Ch\u00e2ssis rentrant Aluminium 120 \u00d7 79 5 exemplaires Avec son certificat d\u2019authenticit\u00e9","og_url":"https:\/\/benoit-barbagli.com\/articles\/sysiphe-collectif-2\/","og_site_name":"benoit-barbagli.com","og_image":[{"width":2560,"height":1680,"url":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2022\/04\/DJI_0837-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/benoit-barbagli.com\/articles\/sysiphe-collectif-2\/","url":"https:\/\/benoit-barbagli.com\/articles\/sysiphe-collectif-2\/","name":"Sysiphe collectif - benoit-barbagli.com","isPartOf":{"@id":"https:\/\/benoit-barbagli.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/benoit-barbagli.com\/articles\/sysiphe-collectif-2\/#primaryimage"},"image":{"@id":"https:\/\/benoit-barbagli.com\/articles\/sysiphe-collectif-2\/#primaryimage"},"thumbnailUrl":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2022\/04\/DJI_0837-scaled-1.jpg","datePublished":"2022-04-18T11:16:16+00:00","breadcrumb":{"@id":"https:\/\/benoit-barbagli.com\/articles\/sysiphe-collectif-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/benoit-barbagli.com\/articles\/sysiphe-collectif-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/benoit-barbagli.com\/articles\/sysiphe-collectif-2\/#primaryimage","url":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2022\/04\/DJI_0837-scaled-1.jpg","contentUrl":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2022\/04\/DJI_0837-scaled-1.jpg","width":2560,"height":1680},{"@type":"BreadcrumbList","@id":"https:\/\/benoit-barbagli.com\/articles\/sysiphe-collectif-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/benoit-barbagli.com\/en\/"},{"@type":"ListItem","position":2,"name":"store","item":"https:\/\/benoit-barbagli.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Sysiphe collectif"}]},{"@type":"WebSite","@id":"https:\/\/benoit-barbagli.com\/en\/#website","url":"https:\/\/benoit-barbagli.com\/en\/","name":"benoit-barbagli.com","description":"Sous le chaos, la vie","publisher":{"@id":"https:\/\/benoit-barbagli.com\/en\/#\/schema\/person\/78c8df9be07e5f4f79d983f84aafeefd"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/benoit-barbagli.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/benoit-barbagli.com\/en\/#\/schema\/person\/78c8df9be07e5f4f79d983f84aafeefd","name":"benoitbarbagli","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2025\/04\/Sisyphe-V-V3-final-scaled.jpg","url":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2025\/04\/Sisyphe-V-V3-final-scaled.jpg","contentUrl":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2025\/04\/Sisyphe-V-V3-final-scaled.jpg","width":1713,"height":2560,"caption":"benoitbarbagli"},"logo":{"@id":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2025\/04\/Sisyphe-V-V3-final-scaled.jpg"}}]}},"_links":{"self":[{"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/product\/75122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/comments?post=75122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/media\/75118"}],"wp:attachment":[{"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/media?parent=75122"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/product_brand?post=75122"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/product_cat?post=75122"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/product_tag?post=75122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}