{"id":912,"count":3,"description":"","link":"https:\/\/benoit-barbagli.com\/en\/categorie-produit\/original-works\/","name":"Original works","slug":"original-works","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Original works - benoit-barbagli.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/benoit-barbagli.com\/en\/categorie-produit\/original-works\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Original works - benoit-barbagli.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/benoit-barbagli.com\/en\/categorie-produit\/original-works\/\" \/>\n<meta property=\"og:site_name\" content=\"benoit-barbagli.com\" \/>\n<meta property=\"og:image\" content=\"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2019\/05\/DSC02317-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/categorie-produit\\\/original-works\\\/\",\"url\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/categorie-produit\\\/original-works\\\/\",\"name\":\"Archives des Original works - benoit-barbagli.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/categorie-produit\\\/original-works\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/categorie-produit\\\/original-works\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oeuvres originales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/\",\"name\":\"benoit-barbagli.com\",\"description\":\"Sous le chaos, la vie\",\"publisher\":{\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/#\\\/schema\\\/person\\\/78c8df9be07e5f4f79d983f84aafeefd\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/#\\\/schema\\\/person\\\/78c8df9be07e5f4f79d983f84aafeefd\",\"name\":\"benoitbarbagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Sisyphe-V-V3-final-scaled.jpg\",\"url\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Sisyphe-V-V3-final-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Sisyphe-V-V3-final-scaled.jpg\",\"width\":1713,\"height\":2560,\"caption\":\"benoitbarbagli\"},\"logo\":{\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Sisyphe-V-V3-final-scaled.jpg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Original works - benoit-barbagli.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/benoit-barbagli.com\/en\/categorie-produit\/original-works\/","og_locale":"en_US","og_type":"article","og_title":"Archives des Original works - benoit-barbagli.com","og_url":"https:\/\/benoit-barbagli.com\/en\/categorie-produit\/original-works\/","og_site_name":"benoit-barbagli.com","og_image":[{"width":2560,"height":1630,"url":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2019\/05\/DSC02317-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/benoit-barbagli.com\/en\/categorie-produit\/original-works\/","url":"https:\/\/benoit-barbagli.com\/en\/categorie-produit\/original-works\/","name":"Archives des Original works - benoit-barbagli.com","isPartOf":{"@id":"https:\/\/benoit-barbagli.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/benoit-barbagli.com\/en\/categorie-produit\/original-works\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/benoit-barbagli.com\/en\/categorie-produit\/original-works\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/benoit-barbagli.com\/en\/"},{"@type":"ListItem","position":2,"name":"Oeuvres originales"}]},{"@type":"WebSite","@id":"https:\/\/benoit-barbagli.com\/en\/#website","url":"https:\/\/benoit-barbagli.com\/en\/","name":"benoit-barbagli.com","description":"Sous le chaos, la vie","publisher":{"@id":"https:\/\/benoit-barbagli.com\/en\/#\/schema\/person\/78c8df9be07e5f4f79d983f84aafeefd"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/benoit-barbagli.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/benoit-barbagli.com\/en\/#\/schema\/person\/78c8df9be07e5f4f79d983f84aafeefd","name":"benoitbarbagli","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2025\/04\/Sisyphe-V-V3-final-scaled.jpg","url":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2025\/04\/Sisyphe-V-V3-final-scaled.jpg","contentUrl":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2025\/04\/Sisyphe-V-V3-final-scaled.jpg","width":1713,"height":2560,"caption":"benoitbarbagli"},"logo":{"@id":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2025\/04\/Sisyphe-V-V3-final-scaled.jpg"}}]}},"_links":{"self":[{"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/product_cat\/912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/product?product_cat=912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}