{"id":91744,"date":"2024-02-03T09:47:27","date_gmt":"2024-02-03T09:47:27","guid":{"rendered":"https:\/\/benoit-barbagli.com\/project\/nouvelle-vague-exhibition-italian-press\/"},"modified":"2024-02-03T09:47:27","modified_gmt":"2024-02-03T09:47:27","slug":"nouvelle-vague-exhibition-italian-press","status":"publish","type":"project","link":"https:\/\/benoit-barbagli.com\/en\/project\/nouvelle-vague-exhibition-italian-press\/","title":{"rendered":"Nouvelle vague exhibition &#8211; Italian Press"},"content":{"rendered":"<h3>Exhibition <em>New Wave<\/em>:<\/h3>\n<p><em>Press web<\/em><\/p>\n<p>French press :<\/p>\n<ul>\n<li><a href=\"https:\/\/lartdenice.blogspot.com\/2022\/04\/benoit-barbagli-nouvelle-vague.html\">Beno\u00eet Barbagli, &#8220;Nouvelle vague&#8221; &#8211; <em>L&#8217;art de nice<\/em> website by Michel Gathier<\/a><\/li>\n<\/ul>\n<p>Italian press:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><a href=\"https:\/\/sguardisutorino.blogspot.com\/2022\/04\/a-palazzo-saluzzo-paesana-la-mostra.html\">Sguardisutorino<\/a><\/li>\n<li><a href=\"https:\/\/www.artribune.com\/mostre-evento-arte\/benoit-barbagli-nouvelle-vague\/\">ArtTribune<\/a><\/li>\n<li><a href=\"https:\/\/www.torinoggi.it\/2022\/04\/09\/leggi-notizia\/argomenti\/eventi-11\/articolo\/palazzo-saluzzo-paesana-riapre-dopo-due-anni-con-la-personale-nouvelle-vague-di-benoit-barbagli.html\">Torinoggi<\/a><\/li>\n<li><a href=\"https:\/\/www.turismotorino.org\/it\/esperienze\/eventi\/nouvelle-vague-personale-di-benoit-barbagli\">Turismotorino<\/a><\/li>\n<li><a href=\"https:\/\/www.torinotoday.it\/eventi\/benoit-barbagli-palazzo-saluzzo-paesana.html\">Torinotoday<\/a><\/li>\n<li><a href=\"https:\/\/www.guidatorino.com\/eventi-torino\/nouvelle-vague-benoit-barbagli-mostra-torino-2022\/\">Guidatorino<\/a><\/li>\n<li><a href=\"https:\/\/torinotopnews.it\/cultura\/palazzo-saluzzo-paesana-ospita-nouvelle-vague-la-mostra-personale-di-benoit-barbagli\/\">torinotopnews<\/a><\/li>\n<li><a href=\"https:\/\/www.quotidianocanavese.it\/lifestyle\/arte--linno-alla-natura-di-benot-barbagli-38044\">Quotidianocanavese<\/a><\/li>\n<li><a href=\"https:\/\/cronacaqui.it\/un-geste-damour-per-i-trecento-anni-di-palazzo-saluzzo\/\">Cronacaqui<\/a><\/li>\n<li><a href=\"https:\/\/www.arte.go.it\/event\/benoit-barbagli-nouvelle-vague\/\">Arte.go<\/a><\/li>\n<li><a href=\"https:\/\/www.mentelocale.it\/torino\/eventi\/207510-nouvelle-vague-benoit-barbagli-mostra-palazzo-saluzzo-paesana.htm\">Mentelocale<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Exhibition New Wave: Press web French press : Beno\u00eet Barbagli, &#8220;Nouvelle vague&#8221; &#8211; L&#8217;art de nice website by Michel Gathier Italian press: &nbsp; Sguardisutorino ArtTribune Torinoggi Turismotorino Torinotoday Guidatorino torinotopnews Quotidianocanavese Cronacaqui Arte.go Mentelocale<\/p>\n","protected":false},"author":1,"featured_media":74980,"comment_status":"open","ping_status":"closed","template":"slidein-personalise","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"project_category":[906,896,897],"project_tag":[],"class_list":["post-91744","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-italian-press","project_category-press-article","project_category-press-web"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nouvelle vague exhibition - Italian Press - benoit-barbagli.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/benoit-barbagli.com\/en\/project\/nouvelle-vague-exhibition-italian-press\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouvelle vague exhibition - Italian Press - benoit-barbagli.com\" \/>\n<meta property=\"og:description\" content=\"Exhibition New Wave: Press web French press : Beno\u00eet Barbagli, &#8220;Nouvelle vague&#8221; &#8211; L&#8217;art de nice website by Michel Gathier Italian press: &nbsp; Sguardisutorino ArtTribune Torinoggi Turismotorino Torinotoday Guidatorino torinotopnews Quotidianocanavese Cronacaqui Arte.go Mentelocale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/benoit-barbagli.com\/en\/project\/nouvelle-vague-exhibition-italian-press\/\" \/>\n<meta property=\"og:site_name\" content=\"benoit-barbagli.com\" \/>\n<meta property=\"og:image\" content=\"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2022\/04\/107_nouvelle_vague-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/project\\\/nouvelle-vague-exhibition-italian-press\\\/\",\"url\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/project\\\/nouvelle-vague-exhibition-italian-press\\\/\",\"name\":\"Nouvelle vague exhibition - Italian Press - benoit-barbagli.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/project\\\/nouvelle-vague-exhibition-italian-press\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/project\\\/nouvelle-vague-exhibition-italian-press\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/107_nouvelle_vague-scaled.jpg\",\"datePublished\":\"2024-02-03T09:47:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/project\\\/nouvelle-vague-exhibition-italian-press\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/project\\\/nouvelle-vague-exhibition-italian-press\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/project\\\/nouvelle-vague-exhibition-italian-press\\\/#primaryimage\",\"url\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/107_nouvelle_vague-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/107_nouvelle_vague-scaled.jpg\",\"width\":1707,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/project\\\/nouvelle-vague-exhibition-italian-press\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projets\",\"item\":\"https:\\\/\\\/benoit-barbagli.com\\\/project\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nouvelle vague exhibition &#8211; Italian Press\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/\",\"name\":\"benoit-barbagli.com\",\"description\":\"Sous le chaos, la vie\",\"publisher\":{\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/#\\\/schema\\\/person\\\/78c8df9be07e5f4f79d983f84aafeefd\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/#\\\/schema\\\/person\\\/78c8df9be07e5f4f79d983f84aafeefd\",\"name\":\"benoitbarbagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Sisyphe-V-V3-final-scaled.jpg\",\"url\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Sisyphe-V-V3-final-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Sisyphe-V-V3-final-scaled.jpg\",\"width\":1713,\"height\":2560,\"caption\":\"benoitbarbagli\"},\"logo\":{\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Sisyphe-V-V3-final-scaled.jpg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouvelle vague exhibition - Italian Press - benoit-barbagli.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/benoit-barbagli.com\/en\/project\/nouvelle-vague-exhibition-italian-press\/","og_locale":"en_US","og_type":"article","og_title":"Nouvelle vague exhibition - Italian Press - benoit-barbagli.com","og_description":"Exhibition New Wave: Press web French press : Beno\u00eet Barbagli, &#8220;Nouvelle vague&#8221; &#8211; L&#8217;art de nice website by Michel Gathier Italian press: &nbsp; Sguardisutorino ArtTribune Torinoggi Turismotorino Torinotoday Guidatorino torinotopnews Quotidianocanavese Cronacaqui Arte.go Mentelocale","og_url":"https:\/\/benoit-barbagli.com\/en\/project\/nouvelle-vague-exhibition-italian-press\/","og_site_name":"benoit-barbagli.com","og_image":[{"width":1707,"height":2560,"url":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2022\/04\/107_nouvelle_vague-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/benoit-barbagli.com\/en\/project\/nouvelle-vague-exhibition-italian-press\/","url":"https:\/\/benoit-barbagli.com\/en\/project\/nouvelle-vague-exhibition-italian-press\/","name":"Nouvelle vague exhibition - Italian Press - benoit-barbagli.com","isPartOf":{"@id":"https:\/\/benoit-barbagli.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/benoit-barbagli.com\/en\/project\/nouvelle-vague-exhibition-italian-press\/#primaryimage"},"image":{"@id":"https:\/\/benoit-barbagli.com\/en\/project\/nouvelle-vague-exhibition-italian-press\/#primaryimage"},"thumbnailUrl":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2022\/04\/107_nouvelle_vague-scaled.jpg","datePublished":"2024-02-03T09:47:27+00:00","breadcrumb":{"@id":"https:\/\/benoit-barbagli.com\/en\/project\/nouvelle-vague-exhibition-italian-press\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/benoit-barbagli.com\/en\/project\/nouvelle-vague-exhibition-italian-press\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/benoit-barbagli.com\/en\/project\/nouvelle-vague-exhibition-italian-press\/#primaryimage","url":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2022\/04\/107_nouvelle_vague-scaled.jpg","contentUrl":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2022\/04\/107_nouvelle_vague-scaled.jpg","width":1707,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/benoit-barbagli.com\/en\/project\/nouvelle-vague-exhibition-italian-press\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/benoit-barbagli.com\/en\/"},{"@type":"ListItem","position":2,"name":"Projets","item":"https:\/\/benoit-barbagli.com\/project\/"},{"@type":"ListItem","position":3,"name":"Nouvelle vague exhibition &#8211; Italian Press"}]},{"@type":"WebSite","@id":"https:\/\/benoit-barbagli.com\/en\/#website","url":"https:\/\/benoit-barbagli.com\/en\/","name":"benoit-barbagli.com","description":"Sous le chaos, la vie","publisher":{"@id":"https:\/\/benoit-barbagli.com\/en\/#\/schema\/person\/78c8df9be07e5f4f79d983f84aafeefd"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/benoit-barbagli.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/benoit-barbagli.com\/en\/#\/schema\/person\/78c8df9be07e5f4f79d983f84aafeefd","name":"benoitbarbagli","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2025\/04\/Sisyphe-V-V3-final-scaled.jpg","url":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2025\/04\/Sisyphe-V-V3-final-scaled.jpg","contentUrl":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2025\/04\/Sisyphe-V-V3-final-scaled.jpg","width":1713,"height":2560,"caption":"benoitbarbagli"},"logo":{"@id":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2025\/04\/Sisyphe-V-V3-final-scaled.jpg"}}]}},"_links":{"self":[{"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/project\/91744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/comments?post=91744"}],"version-history":[{"count":0,"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/project\/91744\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/media\/74980"}],"wp:attachment":[{"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/media?parent=91744"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/project_category?post=91744"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/project_tag?post=91744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}