{"id":91781,"date":"2024-02-03T09:47:40","date_gmt":"2024-02-03T09:47:40","guid":{"rendered":"https:\/\/benoit-barbagli.com\/project\/press-kit-psychopompe-moi\/"},"modified":"2024-02-03T09:47:40","modified_gmt":"2024-02-03T09:47:40","slug":"press-kit-psychopompe-moi","status":"publish","type":"project","link":"https:\/\/benoit-barbagli.com\/en\/oeuvre\/press-kit-psychopompe-moi\/","title":{"rendered":"Press kit &#8211; Psychopompe-moi"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.23&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_fullwidth_post_title meta=&#8221;off&#8221; featured_image=&#8221;off&#8221; _builder_version=&#8221;4.23&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#969696&#8243; background_image=&#8221;https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2023\/11\/111-novembre-2023-scaled.jpg&#8221; height=&#8221;656px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_fullwidth_post_title][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.16&#8243; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_code admin_label=&#8221;Breadcrumb 1.2&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div class=\"custom-breadcrumb\"><\/div><!-- [et_pb_line_break_holder] --><\/p>\n<style>\/*Fil d'ariane*\/<!-- [et_pb_line_break_holder] -->.custom-breadcrumb {<!-- [et_pb_line_break_holder] -->  font-size: 13px;<!-- [et_pb_line_break_holder] -->  color: gray;<!-- [et_pb_line_break_holder] -->  text-align: right;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><\/style>\n<p>[\/et_pb_code][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.23&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1 style=\"text-align: center;\"><span>Psychopomp me  <\/span><\/h1>\n<p style=\"text-align: center;\">Aim\u00e9e Fleury exhibition<\/p>\n<p style=\"text-align: center;\"><span>Opening on Thursday, November 9, 2023 at 12:30 pm by the <\/span><span><br \/>\n  <a class=\"x1i10hfl xjbqb8w x6umtig x1b1mbwd xaqea5y xav7gou x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 x1hl2dhg xggy1nq x1a2a7pz xt0b8zv x1qq9wsj xo1l8bm\" href=\"https:\/\/www.facebook.com\/galerieitinerante.fupaic?__cft__%5B0%5D=AZWwW9wt8xKzqROqWZwBfrbiXWFhtd74g509Nilx-CUunb9nhGTcWNU4_07DigyBGUasyqitREqEAlQpytyRwCt7POipVxzxJPa9bShx7RHWaYvr0ZHkBGmZjaK9aE5yw-LdVJ6_yRUH_36dTfr9fGQJR6blW6Vx42IEBrwhOnWGERJFsgVdauM3wog_4tDDQLuCBYSNpPk8iN6RzTHPrSPxRXd4l4Q3SquBBDXQb4wMR-OmypnpG8OPkBApfXNUjzs&amp;__tn__=-%5DK-R\" role=\"link\" tabindex=\"0\">FUP AIC Itinerant Gallery<\/a><br \/>\n<\/span><\/p>\n<p style=\"text-align: center;\">On view at Arles Galerie de la librairie Actes Sud until November 30.<\/p>\n<p style=\"text-align: center;\">Cocktail reception for the exhibition&#8217;s closing on November 30 at 6pm.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.23&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: center;\">Photographs from the exhibition in zip:<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2023\/11\/vue-exposition-psychopompe-moi-1.zip\" rel=\"attachment wp-att-90920\">vue-exposition-psychopompe-moi-1<\/a><a href=\"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2022\/11\/PRESSE.zip\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.23&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: left;\"><strong>About Aim\u00e9e Fleury and Psychopompe-moi  <\/strong><\/p>\n<p>A mixed-media artist, set designer and photographer born in Paris in 1998, Aim\u00e9e Fleury creates an encounter between the visible and the invisible, exploring the interstices of our contemporary society at the crossroads of art and philosophy. Carrying the stigma of an era in the throes of unprecedented ecological, political and social upheaval. His academic career at Pavillon Bosio, Monaco&#8217;s \u00c9cole sup\u00e9rieure d&#8217;art plastique et de sc\u00e9nographie, forged his atmospheric vision and proselytizing poetics.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Aim\u00e9e Fleury contact information:<\/strong><\/p>\n<p><a href=\"tel:+33%20626197614\">+33 626197614<\/a><\/p>\n<p><a href=\"mailto:aimeefleury@auto-muse.com\">aimeefleury@auto-muse.com<\/a><\/p>\n<p><a href=\"auto-muse.com\">auto-muse.com<\/a><\/p>\n<p><strong>Practical information <\/strong>:  <\/p>\n<ul>\n<li>November 9 to 24, 2023 \/ Tuesday to Saturday \/ 10 a.m. to 7 p.m.<\/li>\n<li>Arles \/ Actes Sud bookshop gallery \/ 47 rue Dr Fanton.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><div class=\"custom-breadcrumb\"><\/div>Psychopomp me Aim\u00e9e Fleury exhibition Opening on Thursday, November 9, 2023 at 12:30 pm by the FUP AIC Itinerant Gallery On view at Arles Galerie de la librairie Actes Sud until November 30. Cocktail reception for the exhibition&#8217;s closing on November 30 at 6pm. &nbsp;Photographs from the exhibition in zip: vue-exposition-psychopompe-moi-1 &nbsp;About Aim\u00e9e Fleury and [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":90594,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"project_category":[895],"project_tag":[],"class_list":["post-91781","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-press-release"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Press kit - Psychopompe-moi - benoit-barbagli.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/benoit-barbagli.com\/en\/oeuvre\/press-kit-psychopompe-moi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Press kit - Psychopompe-moi - benoit-barbagli.com\" \/>\n<meta property=\"og:description\" content=\"Psychopomp me Aim\u00e9e Fleury exhibition Opening on Thursday, November 9, 2023 at 12:30 pm by the FUP AIC Itinerant Gallery On view at Arles Galerie de la librairie Actes Sud until November 30. Cocktail reception for the exhibition&#039;s closing on November 30 at 6pm. &nbsp;Photographs from the exhibition in zip: vue-exposition-psychopompe-moi-1 &nbsp;About Aim\u00e9e Fleury and [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/benoit-barbagli.com\/en\/oeuvre\/press-kit-psychopompe-moi\/\" \/>\n<meta property=\"og:site_name\" content=\"benoit-barbagli.com\" \/>\n<meta property=\"og:image\" content=\"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2023\/11\/111-novembre-2023-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1620\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/oeuvre\\\/press-kit-psychopompe-moi\\\/\",\"url\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/oeuvre\\\/press-kit-psychopompe-moi\\\/\",\"name\":\"Press kit - Psychopompe-moi - benoit-barbagli.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/oeuvre\\\/press-kit-psychopompe-moi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/oeuvre\\\/press-kit-psychopompe-moi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/111-novembre-2023-scaled.jpg\",\"datePublished\":\"2024-02-03T09:47:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/oeuvre\\\/press-kit-psychopompe-moi\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/oeuvre\\\/press-kit-psychopompe-moi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/oeuvre\\\/press-kit-psychopompe-moi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/111-novembre-2023-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/111-novembre-2023-scaled.jpg\",\"width\":2560,\"height\":1620},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/oeuvre\\\/press-kit-psychopompe-moi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projets\",\"item\":\"https:\\\/\\\/benoit-barbagli.com\\\/project\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Press kit &#8211; Psychopompe-moi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/\",\"name\":\"benoit-barbagli.com\",\"description\":\"Sous le chaos, la vie\",\"publisher\":{\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/#\\\/schema\\\/person\\\/78c8df9be07e5f4f79d983f84aafeefd\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/en\\\/#\\\/schema\\\/person\\\/78c8df9be07e5f4f79d983f84aafeefd\",\"name\":\"benoitbarbagli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Sisyphe-V-V3-final-scaled.jpg\",\"url\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Sisyphe-V-V3-final-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Sisyphe-V-V3-final-scaled.jpg\",\"width\":1713,\"height\":2560,\"caption\":\"benoitbarbagli\"},\"logo\":{\"@id\":\"https:\\\/\\\/benoit-barbagli.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Sisyphe-V-V3-final-scaled.jpg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Press kit - Psychopompe-moi - benoit-barbagli.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/benoit-barbagli.com\/en\/oeuvre\/press-kit-psychopompe-moi\/","og_locale":"en_US","og_type":"article","og_title":"Press kit - Psychopompe-moi - benoit-barbagli.com","og_description":"Psychopomp me Aim\u00e9e Fleury exhibition Opening on Thursday, November 9, 2023 at 12:30 pm by the FUP AIC Itinerant Gallery On view at Arles Galerie de la librairie Actes Sud until November 30. Cocktail reception for the exhibition's closing on November 30 at 6pm. &nbsp;Photographs from the exhibition in zip: vue-exposition-psychopompe-moi-1 &nbsp;About Aim\u00e9e Fleury and [&hellip;]","og_url":"https:\/\/benoit-barbagli.com\/en\/oeuvre\/press-kit-psychopompe-moi\/","og_site_name":"benoit-barbagli.com","og_image":[{"width":2560,"height":1620,"url":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2023\/11\/111-novembre-2023-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/benoit-barbagli.com\/en\/oeuvre\/press-kit-psychopompe-moi\/","url":"https:\/\/benoit-barbagli.com\/en\/oeuvre\/press-kit-psychopompe-moi\/","name":"Press kit - Psychopompe-moi - benoit-barbagli.com","isPartOf":{"@id":"https:\/\/benoit-barbagli.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/benoit-barbagli.com\/en\/oeuvre\/press-kit-psychopompe-moi\/#primaryimage"},"image":{"@id":"https:\/\/benoit-barbagli.com\/en\/oeuvre\/press-kit-psychopompe-moi\/#primaryimage"},"thumbnailUrl":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2023\/11\/111-novembre-2023-scaled.jpg","datePublished":"2024-02-03T09:47:40+00:00","breadcrumb":{"@id":"https:\/\/benoit-barbagli.com\/en\/oeuvre\/press-kit-psychopompe-moi\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/benoit-barbagli.com\/en\/oeuvre\/press-kit-psychopompe-moi\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/benoit-barbagli.com\/en\/oeuvre\/press-kit-psychopompe-moi\/#primaryimage","url":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2023\/11\/111-novembre-2023-scaled.jpg","contentUrl":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2023\/11\/111-novembre-2023-scaled.jpg","width":2560,"height":1620},{"@type":"BreadcrumbList","@id":"https:\/\/benoit-barbagli.com\/en\/oeuvre\/press-kit-psychopompe-moi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/benoit-barbagli.com\/en\/"},{"@type":"ListItem","position":2,"name":"Projets","item":"https:\/\/benoit-barbagli.com\/project\/"},{"@type":"ListItem","position":3,"name":"Press kit &#8211; Psychopompe-moi"}]},{"@type":"WebSite","@id":"https:\/\/benoit-barbagli.com\/en\/#website","url":"https:\/\/benoit-barbagli.com\/en\/","name":"benoit-barbagli.com","description":"Sous le chaos, la vie","publisher":{"@id":"https:\/\/benoit-barbagli.com\/en\/#\/schema\/person\/78c8df9be07e5f4f79d983f84aafeefd"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/benoit-barbagli.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/benoit-barbagli.com\/en\/#\/schema\/person\/78c8df9be07e5f4f79d983f84aafeefd","name":"benoitbarbagli","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2025\/04\/Sisyphe-V-V3-final-scaled.jpg","url":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2025\/04\/Sisyphe-V-V3-final-scaled.jpg","contentUrl":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2025\/04\/Sisyphe-V-V3-final-scaled.jpg","width":1713,"height":2560,"caption":"benoitbarbagli"},"logo":{"@id":"https:\/\/benoit-barbagli.com\/wp-content\/uploads\/2025\/04\/Sisyphe-V-V3-final-scaled.jpg"}}]}},"_links":{"self":[{"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/project\/91781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/comments?post=91781"}],"version-history":[{"count":1,"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/project\/91781\/revisions"}],"predecessor-version":[{"id":91784,"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/project\/91781\/revisions\/91784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/media\/90594"}],"wp:attachment":[{"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/media?parent=91781"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/project_category?post=91781"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/benoit-barbagli.com\/en\/wp-json\/wp\/v2\/project_tag?post=91781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}